{"id":4454,"count":1,"description":"","link":"https:\/\/www.gadgetocosmos.com\/el\/tag\/zenbook-duo","name":"Zenbook Duo","slug":"zenbook-duo","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.gadgetocosmos.com\/el\/tag\/zenbook-duo\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4454#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/tag\\\/zenbook-duo#listItem\",\"name\":\"Zenbook Duo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/tag\\\/zenbook-duo#listItem\",\"position\":2,\"name\":\"Zenbook Duo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4454#collectionpage\",\"url\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4454\",\"name\":\"Zenbook Duo - Gadgetocosmos.com\",\"inLanguage\":\"el\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4454#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/#organization\",\"name\":\"Gadgetocosmos.com\",\"description\":\"All about gadgets for everyone!\",\"url\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/\",\"name\":\"Gadgetocosmos.com\",\"alternateName\":\"Gadgetocosmos.com - All about gadgets for everyone!\",\"description\":\"All about gadgets for everyone!\",\"inLanguage\":\"el\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gadgetocosmos.com\\\/el\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Zenbook Duo - Gadgetocosmos.com","description":"","canonical_url":"https:\/\/www.gadgetocosmos.com\/el\/tag\/zenbook-duo","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/tags\/4454#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.gadgetocosmos.com\/el#listItem","position":1,"name":"Home","item":"https:\/\/www.gadgetocosmos.com\/el","nextItem":{"@type":"ListItem","@id":"https:\/\/www.gadgetocosmos.com\/el\/tag\/zenbook-duo#listItem","name":"Zenbook Duo"}},{"@type":"ListItem","@id":"https:\/\/www.gadgetocosmos.com\/el\/tag\/zenbook-duo#listItem","position":2,"name":"Zenbook Duo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.gadgetocosmos.com\/el#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/tags\/4454#collectionpage","url":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/tags\/4454","name":"Zenbook Duo - Gadgetocosmos.com","inLanguage":"el","isPartOf":{"@id":"https:\/\/www.gadgetocosmos.com\/el\/#website"},"breadcrumb":{"@id":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/tags\/4454#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.gadgetocosmos.com\/el\/#organization","name":"Gadgetocosmos.com","description":"All about gadgets for everyone!","url":"https:\/\/www.gadgetocosmos.com\/el\/"},{"@type":"WebSite","@id":"https:\/\/www.gadgetocosmos.com\/el\/#website","url":"https:\/\/www.gadgetocosmos.com\/el\/","name":"Gadgetocosmos.com","alternateName":"Gadgetocosmos.com - All about gadgets for everyone!","description":"All about gadgets for everyone!","inLanguage":"el","publisher":{"@id":"https:\/\/www.gadgetocosmos.com\/el\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.gadgetocosmos.com\/el\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tZenbook Duo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.gadgetocosmos.com\/el"},{"label":"Zenbook Duo","link":"https:\/\/www.gadgetocosmos.com\/el\/tag\/zenbook-duo"}],"_links":{"self":[{"href":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/tags\/4454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.gadgetocosmos.com\/el\/wp-json\/wp\/v2\/posts?tags=4454"}],"curies":[{"name":"\u03b5\u03c1\u03b3\u03b1\u03c3\u03af\u03b1","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}